{"id":3163,"date":"2019-05-25T01:51:14","date_gmt":"2019-05-25T01:51:14","guid":{"rendered":"http:\/\/sailing.thimpress.com\/demo-10\/?page_id=3163"},"modified":"2024-02-15T15:38:27","modified_gmt":"2024-02-15T15:38:27","slug":"galerie","status":"publish","type":"page","link":"https:\/\/villaraggi.it\/fr\/gallery\/","title":{"rendered":"Galerie"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3163\" class=\"elementor elementor-3163\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28f5de7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"28f5de7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27882e4\" data-id=\"27882e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f40d7ae stratum-masonry-gallery-effect-zoom elementor-widget elementor-widget-stratum-masonry-gallery\" data-id=\"f40d7ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"stratum-masonry-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"stratum-masonry-gallery animate_on_scroll masonry-grid effect-2\" data-options=\"{&quot;columns&quot;:3,&quot;gutter&quot;:2,&quot;animate&quot;:true}\">\n\n\t<div class=\"grid-sizer masonry-col-3\"><\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" class=\"wp-image-4595\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-300x200.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-300x200.jpg 300w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-1024x682.jpg 1024w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-0863.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img decoding=\"async\" width=\"300\" height=\"200\" class=\"wp-image-4597\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-300x200.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-300x200.jpg 300w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-1024x683.jpg 1024w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-768x512.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-1536x1025.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866-600x400.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/09\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-200606-1866.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4886\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0026.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4887\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0040.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4889\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0066.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4900\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0162.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4899\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0156.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4902\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0182.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"430\" class=\"wp-image-4903\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-640x430.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-640x430.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-1280x859.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-768x516.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-1536x1031.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262-600x403.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9262.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4904\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9981.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-4905\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-9997.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"429\" class=\"wp-image-4893\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-640x429.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-640x429.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-1280x859.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-768x515.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-1536x1030.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098-600x403.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_Villa-Raggi-ph-merlofotografia-2005-0098.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5328\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_101_002_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5329\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_102_003_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5330\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_001_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5331\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_103_003_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5332\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2015\/10\/jpeg-optimizer_VillaRaggi_105_002_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5382\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_005_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5383\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_006_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5404\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_001_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-scaled.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"640\" class=\"wp-image-5402\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-426x640.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-426x640.jpg 426w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-852x1280.jpg 852w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-768x1154.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-1022x1536.jpg 1022w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-1362x2048.jpg 1362w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-8x12.jpg 8w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-600x902.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_012_HR-scaled.jpg 1703w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5395\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_004_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5393\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_101_002_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5406\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_003_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5407\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_102_004_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5421\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-1280x852.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_103_001_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5448\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_010_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5445\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_007_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5460\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-1280x852.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_001_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t\t\t<div class=\"stratum-masonry-gallery__item masonry-item\">\n\t\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"gallery-6a56ece7c8127\" href=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR.jpg\" class=\"stratum-masonry-gallery__link\">\n\t\t\t                <div class=\"stratum-masonry-gallery__image\">\n                \t<figure>\n                   \t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" class=\"wp-image-5454\" alt=\"\" src=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-640x426.jpg\" srcset=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-640x426.jpg 640w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-1280x851.jpg 1280w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-768x511.jpg 768w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-1536x1022.jpg 1536w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-18x12.jpg 18w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR-600x399.jpg 600w, https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/VillaRaggi_105_016_HR.jpg 1920w\">                \t<\/figure>\n                <\/div>\n                <div class=\"stratum-masonry-gallery__overlay\"><\/div>\n            <\/a>\n        <\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3163","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gallery - Villa Raggi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/villaraggi.it\/fr\/galerie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallery - Villa Raggi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/villaraggi.it\/fr\/galerie\/\" \/>\n<meta property=\"og:site_name\" content=\"Villa Raggi\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T15:38:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/logo-villaraggi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"307\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/villaraggi.it\\\/gallery\\\/\",\"url\":\"https:\\\/\\\/villaraggi.it\\\/gallery\\\/\",\"name\":\"Gallery - Villa Raggi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#website\"},\"datePublished\":\"2019-05-25T01:51:14+00:00\",\"dateModified\":\"2024-02-15T15:38:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/villaraggi.it\\\/gallery\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/villaraggi.it\\\/gallery\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/villaraggi.it\\\/gallery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/villaraggi.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#website\",\"url\":\"https:\\\/\\\/villaraggi.it\\\/\",\"name\":\"Villa Raggi\",\"description\":\"Villa storica del 1700 nell\u2019alto Monferrato, Castelletto d\u2019Orba, Alessandria\",\"publisher\":{\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/villaraggi.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#organization\",\"name\":\"Villa Raggi\",\"url\":\"https:\\\/\\\/villaraggi.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/villaraggi.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-villaraggi.png\",\"contentUrl\":\"https:\\\/\\\/villaraggi.it\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/logo-villaraggi.png\",\"width\":640,\"height\":307,\"caption\":\"Villa Raggi\"},\"image\":{\"@id\":\"https:\\\/\\\/villaraggi.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie - Villa Raggi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/villaraggi.it\/fr\/galerie\/","og_locale":"fr_FR","og_type":"article","og_title":"Gallery - Villa Raggi","og_url":"https:\/\/villaraggi.it\/fr\/galerie\/","og_site_name":"Villa Raggi","article_modified_time":"2024-02-15T15:38:27+00:00","og_image":[{"width":640,"height":307,"url":"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/logo-villaraggi.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/villaraggi.it\/gallery\/","url":"https:\/\/villaraggi.it\/gallery\/","name":"Galerie - Villa Raggi","isPartOf":{"@id":"https:\/\/villaraggi.it\/#website"},"datePublished":"2019-05-25T01:51:14+00:00","dateModified":"2024-02-15T15:38:27+00:00","breadcrumb":{"@id":"https:\/\/villaraggi.it\/gallery\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/villaraggi.it\/gallery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/villaraggi.it\/gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/villaraggi.it\/"},{"@type":"ListItem","position":2,"name":"Gallery"}]},{"@type":"WebSite","@id":"https:\/\/villaraggi.it\/#website","url":"https:\/\/villaraggi.it\/","name":"Villa Raggi","description":"Villa historique des ann\u00e9es 1700 dans le haut Monferrato, Castelletto d'Orba, Alessandria","publisher":{"@id":"https:\/\/villaraggi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/villaraggi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/villaraggi.it\/#organization","name":"Villa Raggi","url":"https:\/\/villaraggi.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/villaraggi.it\/#\/schema\/logo\/image\/","url":"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/logo-villaraggi.png","contentUrl":"https:\/\/villaraggi.it\/wp-content\/uploads\/2024\/02\/logo-villaraggi.png","width":640,"height":307,"caption":"Villa Raggi"},"image":{"@id":"https:\/\/villaraggi.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/pages\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/comments?post=3163"}],"version-history":[{"count":6,"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/pages\/3163\/revisions"}],"predecessor-version":[{"id":7396,"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/pages\/3163\/revisions\/7396"}],"wp:attachment":[{"href":"https:\/\/villaraggi.it\/fr\/wp-json\/wp\/v2\/media?parent=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}